{"id":17072,"date":"2017-12-09T10:38:46","date_gmt":"2017-12-09T09:38:46","guid":{"rendered":"https:\/\/www.tomroc.com\/blog\/?p=17072"},"modified":"2019-05-04T20:27:33","modified_gmt":"2019-05-04T19:27:33","slug":"ouverture-de-la-saison-de-ski-de-randonnee-depuis-fontgillarde","status":"publish","type":"post","link":"https:\/\/www.tomroc.com\/blog\/2017\/12\/ouverture-de-la-saison-de-ski-de-randonnee-depuis-fontgillarde\/","title":{"rendered":"Ouverture de la saison de ski de randonn\u00e9e depuis Fontgillarde"},"content":{"rendered":"<p>Quelle id\u00e9e folle, j&#8217;ai d\u00e9cid\u00e9 de me proposer pour faire dor\u00e9navant de l&#8217;encadrement de sorties de ski de randonn\u00e9e au CAF IDF. Je dispose d&#8217;une solide exp\u00e9rience mais d&#8217;aucune UV, alors je serai co-encadrant avec Thierry B. pour cette premi\u00e8re sortie de d\u00e9but de saison.<\/p>\n<p>Les conditions de neige n&#8217;\u00e9tant pas satisfaisantes sur notre destination initiale \u00e0 Ceillac, notre car est finalement d\u00e9rout\u00e9 \u00e0 Fontgillarde. Nous logerons tous au chalet refuge d&#8217;Alpage Tangeante et ferons des courses en \u00e9toile depuis l\u00e0.<\/p>\n<h1>Samedi &#8211; Cr\u00eate des Chalanchettes (cote 2927m)<\/h1>\n<p>Alors que nous \u00e9tions partis \u00e0 temps de Paris, le car nous d\u00e9pose avec plus d&#8217;une heure trente de retard en ce samedi matin. Alors cela \u00e9limine d&#8217;office toutes les courses un peu trop longues. Il y a un an presque presque jour pour jour nous \u00e9tions \u00e9galement venu \u00e0 Fontgillarde et avions r\u00e9alis\u00e9 la travers\u00e9e vers St Veran en passant par le col du Longet. Alors histoire de varier les plaisirs, nous pr\u00e9voyons cette fois-ci d&#8217;aller plut\u00f4t sur les versants sud, m\u00eame s&#8217;ils sont nettement moins charg\u00e9s en neige.<\/p>\n<p><a  href=\"https:\/\/www.tomroc.com\/blog\/wp-content\/uploads\/20171209-1037-2.jpg\" data-rel=\"lightbox-gallery-0\" data-rl_title=\"20171209-1037-2.jpg\" data-rl_caption=\"\" title=\"20171209-1037-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17153\" src=\"https:\/\/www.tomroc.com\/blog\/wp-content\/uploads\/20171209-1037-2-960x720.jpg\" alt=\"\" width=\"960\" height=\"720\"><\/a><\/p>\n<p>Nous \u00e9voluons \u00e0 flanc dans les pentes et slaloms entre quelques touffes d&#8217;herbes.<\/p>\n<p><a  href=\"https:\/\/www.tomroc.com\/blog\/wp-content\/uploads\/20171209-1117-9.jpg\" data-rel=\"lightbox-gallery-0\" data-rl_title=\"20171209-1117-9.jpg\" data-rl_caption=\"\" title=\"20171209-1117-9.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17154\" src=\"https:\/\/www.tomroc.com\/blog\/wp-content\/uploads\/20171209-1117-9-960x720.jpg\" alt=\"\" width=\"960\" height=\"720\"><\/a><\/p>\n<p>Nous changeons notre objectif initial &#8211; le Pic du fond de Peynin &#8211; pour un somment qui semble atteignable sans trop croiser les touffes d&#8217;herbe. Nous ne sommes d&#8217;ailleurs pas les seuls \u00e0 finir sur cette cr\u00eate, dont nous ne connaissons pas vraiment le nom mais que les conditions de neige ont transform\u00e9 en star de la journ\u00e9e.<\/p>\n<p><a  href=\"https:\/\/www.tomroc.com\/blog\/wp-content\/uploads\/20171209-1428-24.jpg\" data-rel=\"lightbox-gallery-0\" data-rl_title=\"20171209-1428-24.jpg\" data-rl_caption=\"\" title=\"20171209-1428-24.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17155\" src=\"https:\/\/www.tomroc.com\/blog\/wp-content\/uploads\/20171209-1428-24-960x720.jpg\" alt=\"\" width=\"960\" height=\"720\"><\/a><\/p>\n<p><a  href=\"https:\/\/www.tomroc.com\/blog\/wp-content\/uploads\/20171209-1443-28.jpg\" data-rel=\"lightbox-gallery-0\" data-rl_title=\"20171209-1443-28.jpg\" data-rl_caption=\"\" title=\"20171209-1443-28.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17156\" src=\"https:\/\/www.tomroc.com\/blog\/wp-content\/uploads\/20171209-1443-28-960x720.jpg\" alt=\"\" width=\"960\" height=\"720\"><\/a><\/p>\n<p>Au fur et \u00e0 mesure de la descente, la qualit\u00e9 de neige s&#8217;am\u00e9liore et le ski devient de plus en plus sympathique. Au final, il s&#8217;agit d&#8217;une belle journ\u00e9e, bien sauv\u00e9e compte tenu des horaires et conditions.<\/p>\n<h2>Notre parcours<\/h2>\n\t\t<div id=\"maps-marker-pro-703240f7\" class=\"maps-marker-pro\" style=\"width: 100%;\">\n\t\t\t<div id=\"mmp-map-wrap-703240f7\" class=\"mmp-map-wrap\">\n\t\t\t\t\t\t\t\t<div id=\"mmp-map-703240f7\" class=\"mmp-map\" style=\"height: 720px;\"><\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"mmp-chart-wrap-703240f7\" class=\"mmp-gpx-chart-wrap\" style=\"height: 200px;\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\n<ul>\n<li>Distance (km) : 12,7<\/li>\n<li>D\u00e9nivel\u00e9s (m) : +970 -970<\/li>\n<li>Altitudes (m) : mini 1975, maxi 2927<\/li>\n<li>Horaires: d\u00e9part 10h05, retour 16h08<\/li>\n<\/ul>\n<h1>Dimanche &#8211; <a class=\"row-title\" title=\"Modifier le marqueur (309)\" href=\"https:\/\/www.tomroc.com\/blog\/wp-admin\/admin.php?page=leafletmapsmarker_marker&amp;id=309\">Vers le col de Longet<\/a><\/h1>\n<p>La m\u00e9t\u00e9o annon\u00e7ait une journ\u00e9e pourrie et malheureusement elle ne s&#8217;est pas tromp\u00e9e. Il neige en ce dimanche et le ciel est bien bouch\u00e9. Nous d\u00e9cidons d&#8217;aller vers le col du Longet, aussi loin qu&#8217;il nous sera possible.<\/p>\n<p><a  href=\"https:\/\/www.tomroc.com\/blog\/wp-content\/uploads\/20171210-0934-37.jpg\" data-rel=\"lightbox-gallery-0\" data-rl_title=\"20171210-0934-37.jpg\" data-rl_caption=\"\" title=\"20171210-0934-37.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17157\" src=\"https:\/\/www.tomroc.com\/blog\/wp-content\/uploads\/20171210-0934-37-960x720.jpg\" alt=\"\" width=\"960\" height=\"720\"><\/a><\/p>\n<p>Un peu avant le col, et un sondage plus tard, nous d\u00e9cidons le demi-tour et rentrons au refuge.<\/p>\n<p><a  href=\"https:\/\/www.tomroc.com\/blog\/wp-content\/uploads\/20171210-1139-43.jpg\" data-rel=\"lightbox-gallery-0\" data-rl_title=\"20171210-1139-43.jpg\" data-rl_caption=\"\" title=\"20171210-1139-43.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-17158\" src=\"https:\/\/www.tomroc.com\/blog\/wp-content\/uploads\/20171210-1139-43-960x720.jpg\" alt=\"\" width=\"960\" height=\"720\"><\/a><\/p>\n<h2>Notre parcours<\/h2>\n\t\t<div id=\"maps-marker-pro-74a1ffc7\" class=\"maps-marker-pro\" style=\"width: 100%;\">\n\t\t\t<div id=\"mmp-map-wrap-74a1ffc7\" class=\"mmp-map-wrap\">\n\t\t\t\t\t\t\t\t<div id=\"mmp-map-74a1ffc7\" class=\"mmp-map\" style=\"height: 720px;\"><\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"mmp-chart-wrap-74a1ffc7\" class=\"mmp-gpx-chart-wrap\" style=\"height: 200px;\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\n<ul>\n<li>Distance (km) : 9,3<\/li>\n<li>D\u00e9nivel\u00e9s (m) : +510 -510<\/li>\n<li>Altitudes (m) : mini 1975, maxi 2485<\/li>\n<li>Horaires: d\u00e9part 8h50, retour 11h45<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Quelle id\u00e9e folle, j&#8217;ai d\u00e9cid\u00e9 de me proposer pour faire dor\u00e9navant de l&#8217;encadrement de sorties de ski de randonn\u00e9e au CAF IDF. Je dispose d&#8217;une solide exp\u00e9rience mais d&#8217;aucune UV, alors je serai co-encadrant avec Thierry B. pour cette premi\u00e8re sortie de d\u00e9but de saison. Les conditions de neige n&#8217;\u00e9tant pas satisfaisantes sur notre destination [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17153,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[41],"tags":[1256,457,464,809,12,624,452,810],"class_list":["post-17072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-skirando","tag-2-jours","tag-caf","tag-caf-idf","tag-chalet-alpage-tangente","tag-outdoor","tag-sandrine-p","tag-ski-de-randonnee","tag-thierry-b"],"_links":{"self":[{"href":"https:\/\/www.tomroc.com\/blog\/wp-json\/wp\/v2\/posts\/17072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tomroc.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tomroc.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tomroc.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tomroc.com\/blog\/wp-json\/wp\/v2\/comments?post=17072"}],"version-history":[{"count":0,"href":"https:\/\/www.tomroc.com\/blog\/wp-json\/wp\/v2\/posts\/17072\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tomroc.com\/blog\/wp-json\/wp\/v2\/media\/17153"}],"wp:attachment":[{"href":"https:\/\/www.tomroc.com\/blog\/wp-json\/wp\/v2\/media?parent=17072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tomroc.com\/blog\/wp-json\/wp\/v2\/categories?post=17072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tomroc.com\/blog\/wp-json\/wp\/v2\/tags?post=17072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}